{"id":18111,"date":"2024-02-29T17:51:40","date_gmt":"2024-02-29T17:51:40","guid":{"rendered":"https:\/\/test-southcoast-health-multi.southcoast-health.org\/news\/grace-efosa\/"},"modified":"2026-07-08T15:32:04","modified_gmt":"2026-07-08T20:32:04","slug":"grace-efosa","status":"publish","type":"news","link":"https:\/\/www.southcoast.org\/pt\/news\/grace-efosa\/","title":{"rendered":"O Dr. Joseph Lifrak ajuda o jogador de basquetebol dos Friars lesionado a regressar ao campo"},"content":{"rendered":"<p>\"Estava a sofrer imenso\", disse ela. \"Mas Deus aben\u00e7oe o Providence College por me ter posto em contacto com o Dr. Lifrak.\"<\/p>\n\n\n\n<p><a href=\"https:\/\/www.southcoast.org\/pt\/doctors\/joseph-lifrak-md\/#\/appointment-chooser\/providerId\/99992707\/patientTypeId\">Dr. Joseph Lifrak<\/a>, que exerce na Southcoast Health, tamb\u00e9m \u00e9 cirurgi\u00e3o ortop\u00e9dico da <a href=\"https:\/\/friars.com\/index.aspx\">Providence College Friars<\/a> programa desportivo. Diagnosticou a Grace les\u00f5es no ligamento colateral medial (LCM), no ligamento cruzado anterior (LCA) e no menisco.<\/p>\n\n\n\n<p>O LCM e o LCA ajudam a manter o joelho est\u00e1vel, ligando a parte inferior do f\u00e9mur \u00e0 parte superior da t\u00edbia. O LCM encontra-se no lado interior do joelho e o LCA atravessa o centro. O menisco \u00e9 uma cartilagem que actua como amortecedor entre o osso da canela e o f\u00e9mur.<\/p>\n\n\n\n<p>\"Temos quatro ligamentos no joelho e a Grace tinha lesionado dois deles\", disse o Dr. Lifrak. \"Isso tornou a situa\u00e7\u00e3o dela um pouco mais complicada.\"<\/p>\n\n\n\n<p>Grace estava assustada, mas o Dr. Lifrak rapidamente a fez sentir-se confort\u00e1vel e confiante. \"Ele tinha um cora\u00e7\u00e3o caloroso\", disse ela. \"Disse-me que ia cuidar bem de mim.\"<\/p>\n\n\n\n<p>A sua confian\u00e7a aumentou quando o Dr. Lifrak, que jogou basquetebol no liceu, desafiou Grace para um concurso de lan\u00e7amentos livres quando ela recuperou. \"Eu n\u00e3o ia deixar que ele me vencesse nisso\", disse Grace. \"Tinha muitos objectivos ao regressar ao basquetebol. Gra\u00e7as ao desafio do Dr. Lifrak, agora tinha mais um.\"<\/p>\n\n\n\n<p>Inicialmente, o Dr. Lifrak prescreveu a Grace seis semanas de repouso para permitir que a les\u00e3o do LCM sarasse, mas a rotura do LCA exigia uma repara\u00e7\u00e3o cir\u00fargica se ela quisesse continuar a jogar, disse ele. Em abril, realizou um procedimento artrosc\u00f3pico minimamente invasivo que envolveu a cria\u00e7\u00e3o de um novo ligamento com tecido dos ligamentos existentes no joelho<\/p>\n\n\n\n<p>A recupera\u00e7\u00e3o levou nove meses, mas Grace come\u00e7ou os exerc\u00edcios de reabilita\u00e7\u00e3o assim que voltou para o dormit\u00f3rio. O Dr. Lifrak acompanhou o seu progresso enquanto ela se reabilitava com um treinador desportivo dos Friars.<\/p>\n\n\n\n<p>\"Quando se \u00e9 operado, n\u00e3o se pode fazer o b\u00e1sico, como andar ou saltar\", disse ela. \"Com o meu treinador, tive de reaprender esses passos. Isso coloca d\u00favidas na nossa cabe\u00e7a. Nunca se sabe como \u00e9 que se vai voltar. H\u00e1 muitos altos e baixos\".<\/p>\n\n\n\n<p>No entanto, ao sexto m\u00eas, Grace come\u00e7ou a correr e a saltar. E em janeiro de 2022, estava de volta ao campo. Tamb\u00e9m aceitou o desafio de lan\u00e7amento livre do Dr. Lifrak e, apesar de ele a ter vencido por um cesto, Grace liderou a sua equipa em termos de pontua\u00e7\u00e3o na \u00e9poca passada, durante o jogo da \u00e9poca regular da Big East Conference.<\/p>\n\n\n\n<p>Agora, como finalista em Providence, est\u00e1 atualmente na sua \u00faltima \u00e9poca como Friar. Grace continua a visitar o Dr. Lifrak cerca de uma vez por m\u00eas nas cl\u00ednicas semanais que ele organiza para os atletas.<\/p>\n\n\n\n<p>\"Aquilo por que passei trouxe-me muitas li\u00e7\u00f5es\", disse Grace. \"Aprendi a conhecer-me a mim pr\u00f3pria, o meu corpo e a forma como quero encarar a \u00e9poca. Agrade\u00e7o ao Dr. Lifrak e \u00e0 equipa da Southcoast Health por me terem feito voltar ao campo e estar melhor do que nunca.\"<\/p>\n\n\n\n<p><em>Para saber mais sobre os servi\u00e7os ortop\u00e9dicos da Southcoast Health, visite <a href=\"https:\/\/www.southcoast.org\/pt\/services\/orthopedics\/#\/slot-search\/specialtyGroup\/FADF766A-33CC-408D-B94A-0DA797011148\">Tratamentos ortop\u00e9dicos MA &amp; RI | Southcoast Health<\/a><\/em>. <\/p>","protected":false},"author":20,"featured_media":4612,"template":"","categories":[1231],"class_list":["post-18111","news","type-news","status-publish","has-post-thumbnail","hentry","category-patient-stories"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.0 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Southcoast Health Helps Grace Efosa Get Back on the Court - Southcoast Health<\/title>\n<meta name=\"description\" content=\"Grace Efosa, freshman guard for the Providence College women\u2019s basketball team turned to Southcoast Health after an injury on the court.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.southcoast.org\/pt\/news\/grace-efosa\/\" \/>\n<meta property=\"og:locale\" content=\"pt_PT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Southcoast Health Helps Grace Efosa Get Back on the Court - Southcoast Health\" \/>\n<meta property=\"og:description\" content=\"Grace Efosa, freshman guard for the Providence College women\u2019s basketball team turned to Southcoast Health after an injury on the court.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.southcoast.org\/pt\/news\/grace-efosa\/\" \/>\n<meta property=\"og:site_name\" content=\"Southcoast Health\" \/>\n<meta property=\"article:modified_time\" content=\"2026-07-08T20:32:04+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.southcoast.org\/wp-content\/uploads\/2025\/01\/Grace-Efosa-Orthopedics-Patient-Testimonial-2024.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1080\" \/>\n\t<meta property=\"og:image:height\" content=\"566\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.southcoast.org\/news\/grace-efosa\/\",\"url\":\"https:\/\/www.southcoast.org\/news\/grace-efosa\/\",\"name\":\"Southcoast Health Helps Grace Efosa Get Back on the Court - Southcoast Health\",\"isPartOf\":{\"@id\":\"https:\/\/www.southcoast.org\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.southcoast.org\/news\/grace-efosa\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.southcoast.org\/news\/grace-efosa\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.southcoast.org\/wp-content\/uploads\/2025\/01\/Grace-Efosa-Orthopedics-Patient-Testimonial-2024.png\",\"datePublished\":\"2024-02-29T17:51:40+00:00\",\"dateModified\":\"2026-07-08T20:32:04+00:00\",\"description\":\"Grace Efosa, freshman guard for the Providence College women\u2019s basketball team turned to Southcoast Health after an injury on the court.\",\"breadcrumb\":{\"@id\":\"https:\/\/www.southcoast.org\/news\/grace-efosa\/#breadcrumb\"},\"inLanguage\":\"pt-PT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.southcoast.org\/news\/grace-efosa\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\/\/www.southcoast.org\/news\/grace-efosa\/#primaryimage\",\"url\":\"https:\/\/www.southcoast.org\/wp-content\/uploads\/2025\/01\/Grace-Efosa-Orthopedics-Patient-Testimonial-2024.png\",\"contentUrl\":\"https:\/\/www.southcoast.org\/wp-content\/uploads\/2025\/01\/Grace-Efosa-Orthopedics-Patient-Testimonial-2024.png\",\"width\":1080,\"height\":566,\"caption\":\"Two individuals, a smiling woman and a man, posing together and holding a basketball in front of a \\\"More than medicine\\\" backdrop.\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.southcoast.org\/news\/grace-efosa\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"\",\"item\":\"https:\/\/www.southcoast.org\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Dr. Joseph Lifrak Helps Injured Friars Basketball Player Return to the Court\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.southcoast.org\/#website\",\"url\":\"https:\/\/www.southcoast.org\/\",\"name\":\"Southcoast Health\",\"description\":\"More than medicine.\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.southcoast.org\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-PT\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Southcoast Health ajuda Grace Efosa a regressar ao campo - Southcoast Health","description":"Grace Efosa, jogadora da equipa de basquetebol feminino do Providence College, recorreu \u00e0 Southcoast Health ap\u00f3s uma les\u00e3o no campo.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.southcoast.org\/pt\/news\/grace-efosa\/","og_locale":"pt_PT","og_type":"article","og_title":"Southcoast Health Helps Grace Efosa Get Back on the Court - Southcoast Health","og_description":"Grace Efosa, freshman guard for the Providence College women\u2019s basketball team turned to Southcoast Health after an injury on the court.","og_url":"https:\/\/www.southcoast.org\/pt\/news\/grace-efosa\/","og_site_name":"Southcoast Health","article_modified_time":"2026-07-08T20:32:04+00:00","og_image":[{"width":1080,"height":566,"url":"https:\/\/www.southcoast.org\/wp-content\/uploads\/2025\/01\/Grace-Efosa-Orthopedics-Patient-Testimonial-2024.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.southcoast.org\/news\/grace-efosa\/","url":"https:\/\/www.southcoast.org\/news\/grace-efosa\/","name":"Southcoast Health ajuda Grace Efosa a regressar ao campo - Southcoast Health","isPartOf":{"@id":"https:\/\/www.southcoast.org\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.southcoast.org\/news\/grace-efosa\/#primaryimage"},"image":{"@id":"https:\/\/www.southcoast.org\/news\/grace-efosa\/#primaryimage"},"thumbnailUrl":"https:\/\/www.southcoast.org\/wp-content\/uploads\/2025\/01\/Grace-Efosa-Orthopedics-Patient-Testimonial-2024.png","datePublished":"2024-02-29T17:51:40+00:00","dateModified":"2026-07-08T20:32:04+00:00","description":"Grace Efosa, jogadora da equipa de basquetebol feminino do Providence College, recorreu \u00e0 Southcoast Health ap\u00f3s uma les\u00e3o no campo.","breadcrumb":{"@id":"https:\/\/www.southcoast.org\/news\/grace-efosa\/#breadcrumb"},"inLanguage":"pt-PT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.southcoast.org\/news\/grace-efosa\/"]}]},{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/www.southcoast.org\/news\/grace-efosa\/#primaryimage","url":"https:\/\/www.southcoast.org\/wp-content\/uploads\/2025\/01\/Grace-Efosa-Orthopedics-Patient-Testimonial-2024.png","contentUrl":"https:\/\/www.southcoast.org\/wp-content\/uploads\/2025\/01\/Grace-Efosa-Orthopedics-Patient-Testimonial-2024.png","width":1080,"height":566,"caption":"Two individuals, a smiling woman and a man, posing together and holding a basketball in front of a \"More than medicine\" backdrop."},{"@type":"BreadcrumbList","@id":"https:\/\/www.southcoast.org\/news\/grace-efosa\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"","item":"https:\/\/www.southcoast.org\/"},{"@type":"ListItem","position":2,"name":"Dr. Joseph Lifrak Helps Injured Friars Basketball Player Return to the Court"}]},{"@type":"WebSite","@id":"https:\/\/www.southcoast.org\/#website","url":"https:\/\/www.southcoast.org\/","name":"Sa\u00fade no Sudeste","description":"Mais do que medicamentos.","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.southcoast.org\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-PT"}]}},"_links":{"self":[{"href":"https:\/\/www.southcoast.org\/pt\/wp-json\/wp\/v2\/news\/18111","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.southcoast.org\/pt\/wp-json\/wp\/v2\/news"}],"about":[{"href":"https:\/\/www.southcoast.org\/pt\/wp-json\/wp\/v2\/types\/news"}],"author":[{"embeddable":true,"href":"https:\/\/www.southcoast.org\/pt\/wp-json\/wp\/v2\/users\/20"}],"version-history":[{"count":1,"href":"https:\/\/www.southcoast.org\/pt\/wp-json\/wp\/v2\/news\/18111\/revisions"}],"predecessor-version":[{"id":291242,"href":"https:\/\/www.southcoast.org\/pt\/wp-json\/wp\/v2\/news\/18111\/revisions\/291242"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.southcoast.org\/pt\/wp-json\/wp\/v2\/media\/4612"}],"wp:attachment":[{"href":"https:\/\/www.southcoast.org\/pt\/wp-json\/wp\/v2\/media?parent=18111"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.southcoast.org\/pt\/wp-json\/wp\/v2\/categories?post=18111"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}