{"id":18085,"date":"2023-10-31T20:20:37","date_gmt":"2023-10-31T20:20:37","guid":{"rendered":"https:\/\/test-southcoast-health-multi.southcoast-health.org\/news\/lung-story\/"},"modified":"2026-07-08T15:34:40","modified_gmt":"2026-07-08T20:34:40","slug":"lung-story","status":"publish","type":"news","link":"https:\/\/www.southcoast.org\/pt\/news\/lung-story\/","title":{"rendered":"Um rastreio do cancro do pulm\u00e3o salvou a vida de Donna Valois"},"content":{"rendered":"<p>Como ex-fumadora de longa data que tinha deixado de fumar h\u00e1 uma d\u00fazia de anos, Donna era uma boa candidata ao rastreio, que pode detetar o cancro precocemente e dar aos m\u00e9dicos a melhor hip\u00f3tese de o tratar.<\/p>\n\n\n\n<p>No entanto, Donna sentia-se bem e, quando a pandemia de COVID-19 chegou, a obten\u00e7\u00e3o de cuidados tornou-se mais complicada. Acabou por marcar o teste em mar\u00e7o de 2021. O seu check-up anual estava a chegar e \"n\u00e3o queria que o Dr. Barreto ficasse chateado comigo\", disse.<\/p>\n\n\n\n<p>Os resultados chegaram no dia seguinte e eram chocantes. Donna tinha um tumor do tamanho de uma laranja no pulm\u00e3o esquerdo.<\/p>\n\n\n\n<p>\"Nem nos meus sonhos mais loucos pensei que tinha algo de errado comigo\", disse ela. \"N\u00e3o tinha sintomas.<\/p>\n\n\n\n<p>Foi encaminhada para o cirurgi\u00e3o tor\u00e1cico de Southcoast <a href=\"https:\/\/www.southcoast.org\/pt\/doctors\/tammy-gleeson-do\/\">Dra. Tammy Gleeson<\/a> e foi operada no St. Luke's Hospital no final de abril. O Dr. Gleeson retirou cerca de metade do pulm\u00e3o de Donna para extirpar o tumor e alguns n\u00f3dulos cancer\u00edgenos adicionais que encontrou.<\/p>\n\n\n\n<p>\"A Dra. Gleeson disse-me que se eu tivesse esperado mais seis meses, ela estaria a dizer-me quanto tempo tinha de vida\", disse Donna.<\/p>\n\n\n\n<p>Donna passou uma semana no hospital, com o Dr. Gleeson a control\u00e1-la todos os dias. As enfermeiras atenciosas tornaram a sua estadia o mais confort\u00e1vel poss\u00edvel, apesar de os protocolos da COVID-19 restringirem severamente as visitas da irm\u00e3, da filha e do noivo de Donna.<\/p>\n\n\n\n<p><a href=\"https:\/\/www.southcoast.org\/pt\/doctors\/sophia-rizk-md\/\">Dra. Sophia Rizk<\/a>A Dra. Rizk, uma m\u00e9dica oncologista que trabalha no Southcoast em Fall River, a cidade natal de Donna, tamb\u00e9m fazia visitas frequentes ao hospital, mesmo quando n\u00e3o estava de servi\u00e7o. E depois de Donna ter recuperado durante um m\u00eas, o Dr. Rizk supervisionou a sua quimioterapia, que foi administrada no Southcoast Health Fall River Center for Cancer Care. L\u00e1, Donna encontrou \"as melhores e mais gentis enfermeiras de todos os tempos\".<\/p>\n\n\n\n<p>\"A Dra. Rizk foi maravilhosa comigo e muito atenciosa\", disse Donna. \"Explicou-me tudo o que se passava comigo de uma forma que um doente pudesse compreender. E estava sempre dispon\u00edvel.\"<\/p>\n\n\n\n<p>Mesmo assim, as tr\u00eas sess\u00f5es de quimioterapia foram um desafio que a levou ao hospital duas vezes, uma com febre e outra com uma infe\u00e7\u00e3o no sangue. A certa altura, pensou em desistir, mas os amigos e a fam\u00edlia, especialmente Allyson, a sua filha de 21 anos na altura, imploraram-lhe que se mantivesse firme.<\/p>\n\n\n\n<p>\"A minha filha disse: 'M\u00e3e, preciso que fa\u00e7as isto'\", disse Donna. \"Eu faria qualquer coisa por ela.\"<\/p>\n\n\n\n<p>Agora, aos 67 anos, Donna diz que est\u00e1 feliz por estar viva. Ainda est\u00e1 a recuperar as for\u00e7as e est\u00e1 a ser tratada para um enfisema, mas a auto-descrita \"lutadora\" insiste em fazer as suas pr\u00f3prias tarefas dom\u00e9sticas e caminha regularmente com a irm\u00e3 pela orla mar\u00edtima de Fall River. Ao longo de dois anos, aumentou a dist\u00e2ncia que consegue percorrer em duas milhas, mesmo que tenha de parar periodicamente para recuperar o f\u00f4lego.<\/p>\n\n\n\n<p>Retomou o seu trabalho como testadora de software e entrega-se aos seus muitos amores - a praia, a cozinha, os cruzeiros, as viagens, o teatro e os concertos. Faz trabalhos manuais com a irm\u00e3 e a filha, visita a Fl\u00f3rida algumas vezes por ano e est\u00e1 ansiosa por assistir ao casamento da Allyson.<\/p>\n\n\n\n<p>Donna diz que o Dr. Barreto lhe salvou a vida ao incit\u00e1-la a fazer o rastreio e agora estende esse conselho a amigos e familiares.<\/p>\n\n\n\n<p>\"A dete\u00e7\u00e3o precoce \u00e9 tudo\", disse ela \"Se eu tivesse feito um rastreio mais cedo, o tumor poderia ser mais pequeno. Agora fa\u00e7o tudo o que o meu m\u00e9dico me diz e fico feliz por contar a minha hist\u00f3ria se ela salvar uma pessoa. Sinto-me absolutamente maravilhosa\".<\/p>\n\n\n\n<p><em>Para saber mais sobre o rastreio do cancro do pulm\u00e3o na Southcoast Health e na nossa equipa de cirurgia tor\u00e1cica, visite <a href=\"https:\/\/www.southcoast.org\/pt\/services\/cancer-care\/lung-cancer\/\">Tratamento do cancro do pulm\u00e3o MA &amp; RI | Southcoast Health<\/a><\/em>. <\/p>","protected":false},"author":20,"featured_media":4564,"template":"","categories":[1231],"class_list":["post-18085","news","type-news","status-publish","has-post-thumbnail","hentry","category-patient-stories"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.0 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>A Lung Cancer Screening Saved Donna Valois\u2019 Life - Southcoast Health<\/title>\n<meta name=\"description\" content=\"Donna Valois didn\u2019t hurry when her primary care physician, Southcoast Health\u2019s Dr. Felicia Barreto, urged her to be screened for lung cancer in 2019.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.southcoast.org\/pt\/news\/lung-story\/\" \/>\n<meta property=\"og:locale\" content=\"pt_PT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"A Lung Cancer Screening Saved Donna Valois\u2019 Life - Southcoast Health\" \/>\n<meta property=\"og:description\" content=\"Donna Valois didn\u2019t hurry when her primary care physician, Southcoast Health\u2019s Dr. Felicia Barreto, urged her to be screened for lung cancer in 2019.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.southcoast.org\/pt\/news\/lung-story\/\" \/>\n<meta property=\"og:site_name\" content=\"Southcoast Health\" \/>\n<meta property=\"article:modified_time\" content=\"2026-07-08T20:34:40+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.southcoast.org\/wp-content\/uploads\/2025\/01\/EP-5c-scaled-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1851\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.southcoast.org\/news\/lung-story\/\",\"url\":\"https:\/\/www.southcoast.org\/news\/lung-story\/\",\"name\":\"A Lung Cancer Screening Saved Donna Valois\u2019 Life - Southcoast Health\",\"isPartOf\":{\"@id\":\"https:\/\/www.southcoast.org\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.southcoast.org\/news\/lung-story\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.southcoast.org\/news\/lung-story\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.southcoast.org\/wp-content\/uploads\/2025\/01\/EP-5c-scaled-1.jpg\",\"datePublished\":\"2023-10-31T20:20:37+00:00\",\"dateModified\":\"2026-07-08T20:34:40+00:00\",\"description\":\"Donna Valois didn\u2019t hurry when her primary care physician, Southcoast Health\u2019s Dr. Felicia Barreto, urged her to be screened for lung cancer in 2019.\",\"breadcrumb\":{\"@id\":\"https:\/\/www.southcoast.org\/news\/lung-story\/#breadcrumb\"},\"inLanguage\":\"pt-PT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.southcoast.org\/news\/lung-story\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\/\/www.southcoast.org\/news\/lung-story\/#primaryimage\",\"url\":\"https:\/\/www.southcoast.org\/wp-content\/uploads\/2025\/01\/EP-5c-scaled-1.jpg\",\"contentUrl\":\"https:\/\/www.southcoast.org\/wp-content\/uploads\/2025\/01\/EP-5c-scaled-1.jpg\",\"width\":2560,\"height\":1851},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.southcoast.org\/news\/lung-story\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"\",\"item\":\"https:\/\/www.southcoast.org\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"A Lung Cancer Screening Saved Donna Valois\u2019 Life\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.southcoast.org\/#website\",\"url\":\"https:\/\/www.southcoast.org\/\",\"name\":\"Southcoast Health\",\"description\":\"More than medicine.\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.southcoast.org\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-PT\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"A Lung Cancer Screening Saved Donna Valois\u2019 Life - Southcoast Health","description":"Donna Valois didn\u2019t hurry when her primary care physician, Southcoast Health\u2019s Dr. Felicia Barreto, urged her to be screened for lung cancer in 2019.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.southcoast.org\/pt\/news\/lung-story\/","og_locale":"pt_PT","og_type":"article","og_title":"A Lung Cancer Screening Saved Donna Valois\u2019 Life - Southcoast Health","og_description":"Donna Valois didn\u2019t hurry when her primary care physician, Southcoast Health\u2019s Dr. Felicia Barreto, urged her to be screened for lung cancer in 2019.","og_url":"https:\/\/www.southcoast.org\/pt\/news\/lung-story\/","og_site_name":"Southcoast Health","article_modified_time":"2026-07-08T20:34:40+00:00","og_image":[{"width":2560,"height":1851,"url":"https:\/\/www.southcoast.org\/wp-content\/uploads\/2025\/01\/EP-5c-scaled-1.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.southcoast.org\/news\/lung-story\/","url":"https:\/\/www.southcoast.org\/news\/lung-story\/","name":"A Lung Cancer Screening Saved Donna Valois\u2019 Life - Southcoast Health","isPartOf":{"@id":"https:\/\/www.southcoast.org\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.southcoast.org\/news\/lung-story\/#primaryimage"},"image":{"@id":"https:\/\/www.southcoast.org\/news\/lung-story\/#primaryimage"},"thumbnailUrl":"https:\/\/www.southcoast.org\/wp-content\/uploads\/2025\/01\/EP-5c-scaled-1.jpg","datePublished":"2023-10-31T20:20:37+00:00","dateModified":"2026-07-08T20:34:40+00:00","description":"Donna Valois didn\u2019t hurry when her primary care physician, Southcoast Health\u2019s Dr. Felicia Barreto, urged her to be screened for lung cancer in 2019.","breadcrumb":{"@id":"https:\/\/www.southcoast.org\/news\/lung-story\/#breadcrumb"},"inLanguage":"pt-PT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.southcoast.org\/news\/lung-story\/"]}]},{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/www.southcoast.org\/news\/lung-story\/#primaryimage","url":"https:\/\/www.southcoast.org\/wp-content\/uploads\/2025\/01\/EP-5c-scaled-1.jpg","contentUrl":"https:\/\/www.southcoast.org\/wp-content\/uploads\/2025\/01\/EP-5c-scaled-1.jpg","width":2560,"height":1851},{"@type":"BreadcrumbList","@id":"https:\/\/www.southcoast.org\/news\/lung-story\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"","item":"https:\/\/www.southcoast.org\/"},{"@type":"ListItem","position":2,"name":"A Lung Cancer Screening Saved Donna Valois\u2019 Life"}]},{"@type":"WebSite","@id":"https:\/\/www.southcoast.org\/#website","url":"https:\/\/www.southcoast.org\/","name":"Sa\u00fade no Sudeste","description":"Mais do que medicamentos.","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.southcoast.org\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-PT"}]}},"_links":{"self":[{"href":"https:\/\/www.southcoast.org\/pt\/wp-json\/wp\/v2\/news\/18085","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.southcoast.org\/pt\/wp-json\/wp\/v2\/news"}],"about":[{"href":"https:\/\/www.southcoast.org\/pt\/wp-json\/wp\/v2\/types\/news"}],"author":[{"embeddable":true,"href":"https:\/\/www.southcoast.org\/pt\/wp-json\/wp\/v2\/users\/20"}],"version-history":[{"count":1,"href":"https:\/\/www.southcoast.org\/pt\/wp-json\/wp\/v2\/news\/18085\/revisions"}],"predecessor-version":[{"id":291244,"href":"https:\/\/www.southcoast.org\/pt\/wp-json\/wp\/v2\/news\/18085\/revisions\/291244"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.southcoast.org\/pt\/wp-json\/wp\/v2\/media\/4564"}],"wp:attachment":[{"href":"https:\/\/www.southcoast.org\/pt\/wp-json\/wp\/v2\/media?parent=18085"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.southcoast.org\/pt\/wp-json\/wp\/v2\/categories?post=18085"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}