{"id":278214,"date":"2026-03-31T12:31:03","date_gmt":"2026-03-31T17:31:03","guid":{"rendered":"https:\/\/live-southcoast-health-multi.southcoast-health.org\/doctors\/adnan-sultan-mdfacc-facp-fscai-rpvi\/"},"modified":"2026-07-15T05:12:42","modified_gmt":"2026-07-15T10:12:42","slug":"adnan-sultan-mdfacc-facp-fscai-rpvi","status":"publish","type":"doctors","link":"https:\/\/www.southcoast.org\/pt\/doctors\/adnan-sultan-mdfacc-facp-fscai-rpvi\/","title":{"rendered":"Adnan Sultan M\u00e9dico, FACC, FACP, FSCAI, RPVI"},"content":{"rendered":"<div class=\"container\">\n<div class=\"grid\">\n<div class=\"col-sm-12 maincopy blogCore\">\n<p>Adnan Sultan, MD, obteve o seu Bacharelato em Medicina e Cirurgia (MBBS) no The Aga Khan Medical College no Paquist\u00e3o. Em seguida, completou a sua resid\u00eancia em medicina interna na Faculdade de Medicina da Universidade de Indiana antes de completar uma bolsa de estudos em doen\u00e7as cardiovasculares na Faculdade de Medicina da Universidade de Louisville e uma bolsa de estudos em cardiologia de interven\u00e7\u00e3o no Hospital Henry Ford em Detroit, Michigan.&nbsp; &nbsp;<\/p>\n<p>O Dr. Sultan \u00e9 certificado em medicina interna, doen\u00e7as cardiovasculares, cardiologia de interven\u00e7\u00e3o, ecocardiografia e cardiologia nuclear.&nbsp;<\/p>\n<p>Foi atra\u00eddo para a cardiologia de interven\u00e7\u00e3o pela capacidade de influenciar diretamente a vida dos doentes. Nesta especialidade, considera profundamente gratificante a combina\u00e7\u00e3o de procedimentos desafiantes e a ajuda a doentes em situa\u00e7\u00f5es cr\u00edticas, especialmente ao v\u00ea-los recuperar e regressar \u00e0s suas actividades normais ap\u00f3s interven\u00e7\u00f5es que salvam vidas.<\/p>\n<p>O Dr. Sultan pratica medicina com empatia, integridade e um compromisso com a aprendizagem ao longo da vida. O seu objetivo \u00e9 tratar a pessoa como um todo, e n\u00e3o apenas a doen\u00e7a, construindo rela\u00e7\u00f5es fortes, ouvindo as preocupa\u00e7\u00f5es e envolvendo os pacientes nas suas decis\u00f5es de sa\u00fade.<\/p>\n<p>Fazer parte da Southcoast Health f\u00e1-lo sentir que faz parte de uma comunidade que valoriza os cuidados m\u00e9dicos avan\u00e7ados e de vanguarda, mas tamb\u00e9m lhe d\u00e1 a possibilidade de estabelecer rela\u00e7\u00f5es com os doentes.&nbsp;<\/p>\n<p>Fora do trabalho, o Dr. Sultan gosta de esquiar, andar de bicicleta, fazer caminhadas, ler e explorar novos lugares com a sua fam\u00edlia.&nbsp;<\/p>\n<\/div>\n<\/div>\n<\/div>","protected":false},"featured_media":287450,"template":"","specialty":[6,1195],"language":[],"keywords":[],"address":[184,1428],"class_list":["post-278214","doctors","type-doctors","status-publish","has-post-thumbnail","hentry","specialties-cardiology","specialties-interventional-cardiology","addresses-47_258","addresses-47_602"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.0 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Adnan Sultan MD,FACC, FACP, FSCAI, RPVI - Southcoast Health<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.southcoast.org\/pt\/doctors\/adnan-sultan-mdfacc-facp-fscai-rpvi\/\" \/>\n<meta property=\"og:locale\" content=\"pt_PT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Adnan Sultan MD,FACC, FACP, FSCAI, RPVI - Southcoast Health\" \/>\n<meta property=\"og:description\" content=\"Adnan Sultan, MD, earned his Bachelor of Medicine, Bachelor of Surgery (MBBS) from The Aga Khan Medical College in Pakistan. He then completed his residency in internal medicine at the [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.southcoast.org\/pt\/doctors\/adnan-sultan-mdfacc-facp-fscai-rpvi\/\" \/>\n<meta property=\"og:site_name\" content=\"Southcoast Health\" \/>\n<meta property=\"article:modified_time\" content=\"2026-07-15T10:12:42+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.southcoast.org\/wp-content\/uploads\/2026\/03\/sultan-adnan-150x200.png\" \/>\n\t<meta property=\"og:image:width\" content=\"150\" \/>\n\t<meta property=\"og:image:height\" content=\"200\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.southcoast.org\/doctors\/adnan-sultan-mdfacc-facp-fscai-rpvi\/\",\"url\":\"https:\/\/www.southcoast.org\/doctors\/adnan-sultan-mdfacc-facp-fscai-rpvi\/\",\"name\":\"Adnan Sultan MD,FACC, FACP, FSCAI, RPVI - Southcoast Health\",\"isPartOf\":{\"@id\":\"https:\/\/www.southcoast.org\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.southcoast.org\/doctors\/adnan-sultan-mdfacc-facp-fscai-rpvi\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.southcoast.org\/doctors\/adnan-sultan-mdfacc-facp-fscai-rpvi\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.southcoast.org\/wp-content\/uploads\/2026\/03\/sultan-adnan-150x200.png\",\"datePublished\":\"2026-03-31T17:31:03+00:00\",\"dateModified\":\"2026-07-15T10:12:42+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.southcoast.org\/doctors\/adnan-sultan-mdfacc-facp-fscai-rpvi\/#breadcrumb\"},\"inLanguage\":\"pt-PT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.southcoast.org\/doctors\/adnan-sultan-mdfacc-facp-fscai-rpvi\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\/\/www.southcoast.org\/doctors\/adnan-sultan-mdfacc-facp-fscai-rpvi\/#primaryimage\",\"url\":\"https:\/\/www.southcoast.org\/wp-content\/uploads\/2026\/03\/sultan-adnan-150x200.png\",\"contentUrl\":\"https:\/\/www.southcoast.org\/wp-content\/uploads\/2026\/03\/sultan-adnan-150x200.png\",\"width\":150,\"height\":200,\"caption\":\"Headshot of provider Adnan Sultan MD,FACC, FACP, FSCAI, RPVI\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.southcoast.org\/doctors\/adnan-sultan-mdfacc-facp-fscai-rpvi\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"\",\"item\":\"https:\/\/www.southcoast.org\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Doctors\",\"item\":\"https:\/\/www.southcoast.org\/doctors\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Adnan Sultan MD,FACC, FACP, FSCAI, RPVI\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.southcoast.org\/#website\",\"url\":\"https:\/\/www.southcoast.org\/\",\"name\":\"Southcoast Health\",\"description\":\"More than medicine.\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.southcoast.org\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-PT\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Adnan Sultan MD,FACC, FACP, FSCAI, RPVI - Southcoast Health","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.southcoast.org\/pt\/doctors\/adnan-sultan-mdfacc-facp-fscai-rpvi\/","og_locale":"pt_PT","og_type":"article","og_title":"Adnan Sultan MD,FACC, FACP, FSCAI, RPVI - Southcoast Health","og_description":"Adnan Sultan, MD, earned his Bachelor of Medicine, Bachelor of Surgery (MBBS) from The Aga Khan Medical College in Pakistan. He then completed his residency in internal medicine at the [&hellip;]","og_url":"https:\/\/www.southcoast.org\/pt\/doctors\/adnan-sultan-mdfacc-facp-fscai-rpvi\/","og_site_name":"Southcoast Health","article_modified_time":"2026-07-15T10:12:42+00:00","og_image":[{"width":150,"height":200,"url":"https:\/\/www.southcoast.org\/wp-content\/uploads\/2026\/03\/sultan-adnan-150x200.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.southcoast.org\/doctors\/adnan-sultan-mdfacc-facp-fscai-rpvi\/","url":"https:\/\/www.southcoast.org\/doctors\/adnan-sultan-mdfacc-facp-fscai-rpvi\/","name":"Adnan Sultan MD,FACC, FACP, FSCAI, RPVI - Southcoast Health","isPartOf":{"@id":"https:\/\/www.southcoast.org\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.southcoast.org\/doctors\/adnan-sultan-mdfacc-facp-fscai-rpvi\/#primaryimage"},"image":{"@id":"https:\/\/www.southcoast.org\/doctors\/adnan-sultan-mdfacc-facp-fscai-rpvi\/#primaryimage"},"thumbnailUrl":"https:\/\/www.southcoast.org\/wp-content\/uploads\/2026\/03\/sultan-adnan-150x200.png","datePublished":"2026-03-31T17:31:03+00:00","dateModified":"2026-07-15T10:12:42+00:00","breadcrumb":{"@id":"https:\/\/www.southcoast.org\/doctors\/adnan-sultan-mdfacc-facp-fscai-rpvi\/#breadcrumb"},"inLanguage":"pt-PT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.southcoast.org\/doctors\/adnan-sultan-mdfacc-facp-fscai-rpvi\/"]}]},{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/www.southcoast.org\/doctors\/adnan-sultan-mdfacc-facp-fscai-rpvi\/#primaryimage","url":"https:\/\/www.southcoast.org\/wp-content\/uploads\/2026\/03\/sultan-adnan-150x200.png","contentUrl":"https:\/\/www.southcoast.org\/wp-content\/uploads\/2026\/03\/sultan-adnan-150x200.png","width":150,"height":200,"caption":"Headshot of provider Adnan Sultan MD,FACC, FACP, FSCAI, RPVI"},{"@type":"BreadcrumbList","@id":"https:\/\/www.southcoast.org\/doctors\/adnan-sultan-mdfacc-facp-fscai-rpvi\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"","item":"https:\/\/www.southcoast.org\/"},{"@type":"ListItem","position":2,"name":"Doctors","item":"https:\/\/www.southcoast.org\/doctors\/"},{"@type":"ListItem","position":3,"name":"Adnan Sultan MD,FACC, FACP, FSCAI, RPVI"}]},{"@type":"WebSite","@id":"https:\/\/www.southcoast.org\/#website","url":"https:\/\/www.southcoast.org\/","name":"Sa\u00fade no Sudeste","description":"Mais do que medicamentos.","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.southcoast.org\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-PT"}]}},"_links":{"self":[{"href":"https:\/\/www.southcoast.org\/pt\/wp-json\/wp\/v2\/doctors\/278214","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.southcoast.org\/pt\/wp-json\/wp\/v2\/doctors"}],"about":[{"href":"https:\/\/www.southcoast.org\/pt\/wp-json\/wp\/v2\/types\/doctors"}],"version-history":[{"count":1,"href":"https:\/\/www.southcoast.org\/pt\/wp-json\/wp\/v2\/doctors\/278214\/revisions"}],"predecessor-version":[{"id":279229,"href":"https:\/\/www.southcoast.org\/pt\/wp-json\/wp\/v2\/doctors\/278214\/revisions\/279229"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.southcoast.org\/pt\/wp-json\/wp\/v2\/media\/287450"}],"wp:attachment":[{"href":"https:\/\/www.southcoast.org\/pt\/wp-json\/wp\/v2\/media?parent=278214"}],"wp:term":[{"taxonomy":"specialties","embeddable":true,"href":"https:\/\/www.southcoast.org\/pt\/wp-json\/wp\/v2\/specialty?post=278214"},{"taxonomy":"languages","embeddable":true,"href":"https:\/\/www.southcoast.org\/pt\/wp-json\/wp\/v2\/language?post=278214"},{"taxonomy":"keywords","embeddable":true,"href":"https:\/\/www.southcoast.org\/pt\/wp-json\/wp\/v2\/keywords?post=278214"},{"taxonomy":"addresses","embeddable":true,"href":"https:\/\/www.southcoast.org\/pt\/wp-json\/wp\/v2\/address?post=278214"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}