{"id":18138,"date":"2024-05-21T21:04:47","date_gmt":"2024-05-21T21:04:47","guid":{"rendered":"https:\/\/test-southcoast-health-multi.southcoast-health.org\/news\/tobey-ed\/"},"modified":"2026-07-08T15:30:00","modified_gmt":"2026-07-08T20:30:00","slug":"tobey-ed","status":"publish","type":"news","link":"https:\/\/www.southcoast.org\/es\/news\/tobey-ed\/","title":{"rendered":"Una pareja de Bourne descubre el servicio de urgencias del Hospital Tobey, que salva vidas"},"content":{"rendered":"<p>David remonta su problema a cinco a\u00f1os antes, cuando un a\u00f1o de tratamientos de inmunoterapia para un melanoma metast\u00e1sico le dej\u00f3 con insuficiencia suprarrenal. Esta afecci\u00f3n reduce su capacidad para combatir enfermedades porque sus gl\u00e1ndulas suprarrenales no pueden producir cortisol, que reduce la inflamaci\u00f3n.<\/p>\n\n\n\n<p>COVID mantuvo a David en casa durante una semana antes de que se sintiera lo suficientemente bien como para reanudar sus funciones como vicepresidente de <a href=\"https:\/\/www.bristolcountysavings.com\/\">Caja de Ahorros del Condado de Bristol<\/a>. Pero al cabo de una semana de volver a la oficina, David empez\u00f3 a sufrir fatiga, debilidad, fiebre y dolores corporales. Con n\u00e1useas y mareos, se desplom\u00f3 en el suelo del ba\u00f1o de su casa y no sab\u00eda d\u00f3nde estaba.<\/p>\n\n\n\n<p>\"Estaba muy asustada\", dijo su esposa, Ann McCrillis Tipping, que decidi\u00f3 llamar a una ambulancia, a pesar de la resistencia de su marido, que insist\u00eda en que se encontraba bien.<\/p>\n\n\n\n<p>\"Tienen que entender que normalmente soy una persona independiente, en\u00e9rgica y de car\u00e1cter fuerte\", dijo David. \"Nunca he experimentado nada parecido en mi vida y espero no volver a hacerlo\".<\/p>\n\n\n\n<p>Desde el momento en que la ambulancia se detuvo en la casa de la pareja en Bourne, Ann sinti\u00f3 que estaban en buenas manos, aunque se preocup\u00f3 cuando los param\u00e9dicos le dijeron que iban a llevar a David al hospital. <a href=\"https:\/\/www.southcoast.org\/es\/locations\/emergency-services-tobey\/\">Servicio de Urgencias del Hospital Tobey.<\/a><\/p>\n\n\n\n<p>\"Nunca hab\u00edamos estado en Tobey, as\u00ed que estaba un poco nerviosa\", dijo. \"Pero los param\u00e9dicos fueron extraordinarios. Cuando la ambulancia lleg\u00f3 al hospital, nos esperaba una enfermera, y a partir de ah\u00ed todo fue bien.\"<\/p>\n\n\n\n<p>El principal temor de Ann era que el complicado historial m\u00e9dico de su marido, que se desarroll\u00f3 principalmente en hospitales de Boston, fuera desconocido para los proveedores de Tobey. Se sinti\u00f3 aliviada al ver que pod\u00edan acceder a todo su historial asistencial a trav\u00e9s de Epic, el sistema de historia cl\u00ednica electr\u00f3nica que utilizan los hospitales de todo el pa\u00eds.<\/p>\n\n\n\n<p>Las pruebas revelaron que David ten\u00eda una infecci\u00f3n urinaria y sufr\u00eda sepsis grave, una enfermedad potencialmente mortal que implica una respuesta demasiado agresiva a la infecci\u00f3n que impide que los \u00f3rganos del cuerpo funcionen correctamente.<\/p>\n\n\n\n<p>\"Le pregunt\u00e9 al m\u00e9dico de urgencias <a href=\"https:\/\/www.southcoast.org\/es\/doctors\/michael-grossman-md\/\">Dra. Michele Grossman <\/a>que nos dijera exactamente lo que quer\u00eda decir\", dijo Ann. \"No quer\u00eda o\u00edr palabras m\u00e9dicas, sino que hablara claro. Nos dijo: 'Est\u00e1 en estado cr\u00edtico y estamos tomando medidas para salvarle la vida'. As\u00ed entendimos mejor lo que estaba pasando\".\u00a0\u00a0<\/p>\n\n\n\n<p>David se estabiliz\u00f3 lo suficiente en urgencias para ser trasladado a la Unidad de Cuidados Intensivos, donde pas\u00f3 tres d\u00edas. Tras otros tres d\u00edas en una planta general, le dieron el alta para volver a casa. Tres semanas despu\u00e9s, volvi\u00f3 al trabajo y, con la mejora del tiempo, ahora espera con impaciencia un verano de kayak, pesca y otras actividades acu\u00e1ticas.\u00a0<\/p>\n\n\n\n<p>\"Todo el mundo -los t\u00e9cnicos de urgencias, las enfermeras, los t\u00e9cnicos, el Dr. Grossman y el Dr. Ajith Matthew- fue fant\u00e1stico\", dijo David. \"Estuvieron atentos y respondieron a mis preguntas. Gracias a su trabajo en equipo y a su cooperaci\u00f3n, diagnosticaron r\u00e1pidamente mi problema. Epic les permiti\u00f3 acceder a mi historial m\u00e9dico. No tengo palabras\".<\/p>\n\n\n\n<p>A Ann tambi\u00e9n le gust\u00f3 que el Hospital Tobey estuviera cerca. \"Definitivamente volveremos a Tobey si necesitamos atenci\u00f3n hospitalaria. Sin duda le dir\u00eda a cualquiera que fuera al Hospital Tobey. Todos los que participaron en la atenci\u00f3n de Dave fueron excelentes\".<\/p>\n\n\n\n<p><\/p>","protected":false},"author":20,"featured_media":4655,"template":"","categories":[1231],"class_list":["post-18138","news","type-news","status-publish","has-post-thumbnail","hentry","category-patient-stories"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.0 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Bourne Couple Discovers Tobey Hospitals Lifesaving ED - Southcoast Health<\/title>\n<meta name=\"description\" content=\"David Tipping thought he\u2019d recovered from COVID in October 2023, but the disease had hit him harder than he knew, and he soon found himself fighting for his life in the Tobey Hospital Emergency Department.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.southcoast.org\/es\/news\/tobey-ed\/\" \/>\n<meta property=\"og:locale\" content=\"es_MX\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Bourne Couple Discovers Tobey Hospitals Lifesaving ED - Southcoast Health\" \/>\n<meta property=\"og:description\" content=\"David Tipping thought he\u2019d recovered from COVID in October 2023, but the disease had hit him harder than he knew, and he soon found himself fighting for his life in the Tobey Hospital Emergency Department.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.southcoast.org\/es\/news\/tobey-ed\/\" \/>\n<meta property=\"og:site_name\" content=\"Southcoast Health\" \/>\n<meta property=\"article:modified_time\" content=\"2026-07-08T20:30:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.southcoast.org\/wp-content\/uploads\/2025\/01\/Ann-David-Tipping.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1080\" \/>\n\t<meta property=\"og:image:height\" content=\"566\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.southcoast.org\/news\/tobey-ed\/\",\"url\":\"https:\/\/www.southcoast.org\/news\/tobey-ed\/\",\"name\":\"Bourne Couple Discovers Tobey Hospitals Lifesaving ED - Southcoast Health\",\"isPartOf\":{\"@id\":\"https:\/\/www.southcoast.org\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.southcoast.org\/news\/tobey-ed\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.southcoast.org\/news\/tobey-ed\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.southcoast.org\/wp-content\/uploads\/2025\/01\/Ann-David-Tipping.png\",\"datePublished\":\"2024-05-21T21:04:47+00:00\",\"dateModified\":\"2026-07-08T20:30:00+00:00\",\"description\":\"David Tipping thought he\u2019d recovered from COVID in October 2023, but the disease had hit him harder than he knew, and he soon found himself fighting for his life in the Tobey Hospital Emergency Department.\",\"breadcrumb\":{\"@id\":\"https:\/\/www.southcoast.org\/news\/tobey-ed\/#breadcrumb\"},\"inLanguage\":\"es-MX\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.southcoast.org\/news\/tobey-ed\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es-MX\",\"@id\":\"https:\/\/www.southcoast.org\/news\/tobey-ed\/#primaryimage\",\"url\":\"https:\/\/www.southcoast.org\/wp-content\/uploads\/2025\/01\/Ann-David-Tipping.png\",\"contentUrl\":\"https:\/\/www.southcoast.org\/wp-content\/uploads\/2025\/01\/Ann-David-Tipping.png\",\"width\":1080,\"height\":566,\"caption\":\"A smiling middle-aged couple poses in a comfortable home setting.\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.southcoast.org\/news\/tobey-ed\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"\",\"item\":\"https:\/\/www.southcoast.org\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"A Bourne Couple Discovers Tobey Hospital\u2019s Lifesaving Emergency Department\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.southcoast.org\/#website\",\"url\":\"https:\/\/www.southcoast.org\/\",\"name\":\"Southcoast Health\",\"description\":\"More than medicine.\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.southcoast.org\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es-MX\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Bourne Couple Discovers Tobey Hospitals Lifesaving ED - Southcoast Health","description":"David Tipping thought he\u2019d recovered from COVID in October 2023, but the disease had hit him harder than he knew, and he soon found himself fighting for his life in the Tobey Hospital Emergency Department.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.southcoast.org\/es\/news\/tobey-ed\/","og_locale":"es_MX","og_type":"article","og_title":"Bourne Couple Discovers Tobey Hospitals Lifesaving ED - Southcoast Health","og_description":"David Tipping thought he\u2019d recovered from COVID in October 2023, but the disease had hit him harder than he knew, and he soon found himself fighting for his life in the Tobey Hospital Emergency Department.","og_url":"https:\/\/www.southcoast.org\/es\/news\/tobey-ed\/","og_site_name":"Southcoast Health","article_modified_time":"2026-07-08T20:30:00+00:00","og_image":[{"width":1080,"height":566,"url":"https:\/\/www.southcoast.org\/wp-content\/uploads\/2025\/01\/Ann-David-Tipping.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.southcoast.org\/news\/tobey-ed\/","url":"https:\/\/www.southcoast.org\/news\/tobey-ed\/","name":"Bourne Couple Discovers Tobey Hospitals Lifesaving ED - Southcoast Health","isPartOf":{"@id":"https:\/\/www.southcoast.org\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.southcoast.org\/news\/tobey-ed\/#primaryimage"},"image":{"@id":"https:\/\/www.southcoast.org\/news\/tobey-ed\/#primaryimage"},"thumbnailUrl":"https:\/\/www.southcoast.org\/wp-content\/uploads\/2025\/01\/Ann-David-Tipping.png","datePublished":"2024-05-21T21:04:47+00:00","dateModified":"2026-07-08T20:30:00+00:00","description":"David Tipping thought he\u2019d recovered from COVID in October 2023, but the disease had hit him harder than he knew, and he soon found himself fighting for his life in the Tobey Hospital Emergency Department.","breadcrumb":{"@id":"https:\/\/www.southcoast.org\/news\/tobey-ed\/#breadcrumb"},"inLanguage":"es-MX","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.southcoast.org\/news\/tobey-ed\/"]}]},{"@type":"ImageObject","inLanguage":"es-MX","@id":"https:\/\/www.southcoast.org\/news\/tobey-ed\/#primaryimage","url":"https:\/\/www.southcoast.org\/wp-content\/uploads\/2025\/01\/Ann-David-Tipping.png","contentUrl":"https:\/\/www.southcoast.org\/wp-content\/uploads\/2025\/01\/Ann-David-Tipping.png","width":1080,"height":566,"caption":"A smiling middle-aged couple poses in a comfortable home setting."},{"@type":"BreadcrumbList","@id":"https:\/\/www.southcoast.org\/news\/tobey-ed\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"","item":"https:\/\/www.southcoast.org\/"},{"@type":"ListItem","position":2,"name":"A Bourne Couple Discovers Tobey Hospital\u2019s Lifesaving Emergency Department"}]},{"@type":"WebSite","@id":"https:\/\/www.southcoast.org\/#website","url":"https:\/\/www.southcoast.org\/","name":"Southcoast Health","description":"M\u00e1s que medicina.","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.southcoast.org\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es-MX"}]}},"_links":{"self":[{"href":"https:\/\/www.southcoast.org\/es\/wp-json\/wp\/v2\/news\/18138","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.southcoast.org\/es\/wp-json\/wp\/v2\/news"}],"about":[{"href":"https:\/\/www.southcoast.org\/es\/wp-json\/wp\/v2\/types\/news"}],"author":[{"embeddable":true,"href":"https:\/\/www.southcoast.org\/es\/wp-json\/wp\/v2\/users\/20"}],"version-history":[{"count":1,"href":"https:\/\/www.southcoast.org\/es\/wp-json\/wp\/v2\/news\/18138\/revisions"}],"predecessor-version":[{"id":291239,"href":"https:\/\/www.southcoast.org\/es\/wp-json\/wp\/v2\/news\/18138\/revisions\/291239"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.southcoast.org\/es\/wp-json\/wp\/v2\/media\/4655"}],"wp:attachment":[{"href":"https:\/\/www.southcoast.org\/es\/wp-json\/wp\/v2\/media?parent=18138"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.southcoast.org\/es\/wp-json\/wp\/v2\/categories?post=18138"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}