{"id":278320,"date":"2026-03-31T12:47:44","date_gmt":"2026-03-31T17:47:44","guid":{"rendered":"https:\/\/live-southcoast-health-multi.southcoast-health.org\/doctors\/lesly-wood-dnp\/"},"modified":"2026-07-15T05:01:40","modified_gmt":"2026-07-15T10:01:40","slug":"lesly-wood-dnp","status":"publish","type":"doctors","link":"https:\/\/www.southcoast.org\/es\/doctors\/lesly-wood-dnp\/","title":{"rendered":"Lesly Wood DNP"},"content":{"rendered":"<div class=\"container\">\n<div class=\"grid\">\n<div class=\"col-sm-12 maincopy blogCore\">\n<p>Lesly Wood, DNP, se licenci\u00f3 en Providence College en Providence, Rhode Island. A continuaci\u00f3n, obtuvo el t\u00edtulo de Asociada en Ciencias de Enfermer\u00eda en el Bristol Community College de Fall River, Massachusetts, antes de avanzar en su formaci\u00f3n cl\u00ednica, obteniendo el t\u00edtulo de Doctora en Pr\u00e1ctica de Enfermer\u00eda en UMass Dartmouth.&nbsp;<\/p>\n<p>Le gusta la cirug\u00eda vascular porque es un campo que combina la atenci\u00f3n m\u00e9dica y quir\u00fargica. Le atraen sus exigencias de precisi\u00f3n, pensamiento cr\u00edtico y colaboraci\u00f3n.&nbsp;<\/p>\n<p>En su pr\u00e1ctica, el enfoque centrado en el paciente de Lesly hace hincapi\u00e9 en la excelencia cl\u00ednica, la empat\u00eda y el tratamiento individualizado basado en pruebas, abordando todo el espectro de necesidades f\u00edsicas, emocionales, mentales y sociales. Ella encuentra un profundo prop\u00f3sito en ayudar a sus pacientes a recuperar la movilidad y la independencia a trav\u00e9s de desaf\u00edos que alteran la vida. Lesly desarrolla relaciones de colaboraci\u00f3n con pacientes, familiares y diversos equipos sanitarios para garantizar una atenci\u00f3n de alta calidad.<\/p>\n<div>Southcoast Health tiene un significado personal y profesional para ella. Su padre fue m\u00e9dico de atenci\u00f3n primaria en el sistema, y su abuela trabaj\u00f3 anteriormente como asistente m\u00e9dica. Formar parte de la organizaci\u00f3n representa la continuaci\u00f3n del legado de su familia en la atenci\u00f3n basada en la comunidad.&nbsp;<\/div>\n<div><\/div>\n<div>Cuando no est\u00e1 atendiendo a pacientes, Lesly disfruta pasando tiempo con su familia, especialmente con sus sobrinas y sobrinos, as\u00ed como con sus mascotas. Le encantan los viajes internacionales y la exploraci\u00f3n cultural. Ha participado en varias misiones m\u00e9dicas internacionales en Tanzania, Honduras y Hait\u00ed.&nbsp;<\/div>\n<\/p>\n<\/div>\n<\/div>\n<\/div>","protected":false},"featured_media":288007,"template":"","specialty":[202],"language":[],"keywords":[],"address":[79,78,201],"class_list":["post-278320","doctors","type-doctors","status-publish","has-post-thumbnail","hentry","specialties-vascular-surgery","addresses-103_134","addresses-194_340","addresses-55_160"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.0 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Lesly Wood DNP - Southcoast Health<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.southcoast.org\/es\/doctors\/lesly-wood-dnp\/\" \/>\n<meta property=\"og:locale\" content=\"es_MX\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Lesly Wood DNP - Southcoast Health\" \/>\n<meta property=\"og:description\" content=\"Lesly Wood, DNP, earned her Bachelor of Arts from Providence College in Providence, Rhode Island. She then went on to obtain her Associate in Science in Nursing from Bristol Community [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.southcoast.org\/es\/doctors\/lesly-wood-dnp\/\" \/>\n<meta property=\"og:site_name\" content=\"Southcoast Health\" \/>\n<meta property=\"article:modified_time\" content=\"2026-07-15T10:01:40+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.southcoast.org\/wp-content\/uploads\/2026\/03\/wood-lesly-150x200.png\" \/>\n\t<meta property=\"og:image:width\" content=\"150\" \/>\n\t<meta property=\"og:image:height\" content=\"200\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.southcoast.org\/doctors\/lesly-wood-dnp\/\",\"url\":\"https:\/\/www.southcoast.org\/doctors\/lesly-wood-dnp\/\",\"name\":\"Lesly Wood DNP - Southcoast Health\",\"isPartOf\":{\"@id\":\"https:\/\/www.southcoast.org\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.southcoast.org\/doctors\/lesly-wood-dnp\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.southcoast.org\/doctors\/lesly-wood-dnp\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.southcoast.org\/wp-content\/uploads\/2026\/03\/wood-lesly-150x200.png\",\"datePublished\":\"2026-03-31T17:47:44+00:00\",\"dateModified\":\"2026-07-15T10:01:40+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.southcoast.org\/doctors\/lesly-wood-dnp\/#breadcrumb\"},\"inLanguage\":\"es-MX\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.southcoast.org\/doctors\/lesly-wood-dnp\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es-MX\",\"@id\":\"https:\/\/www.southcoast.org\/doctors\/lesly-wood-dnp\/#primaryimage\",\"url\":\"https:\/\/www.southcoast.org\/wp-content\/uploads\/2026\/03\/wood-lesly-150x200.png\",\"contentUrl\":\"https:\/\/www.southcoast.org\/wp-content\/uploads\/2026\/03\/wood-lesly-150x200.png\",\"width\":150,\"height\":200,\"caption\":\"Headshot of provider Lesly Wood DNP\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.southcoast.org\/doctors\/lesly-wood-dnp\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"\",\"item\":\"https:\/\/www.southcoast.org\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Doctors\",\"item\":\"https:\/\/www.southcoast.org\/doctors\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Lesly Wood DNP\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.southcoast.org\/#website\",\"url\":\"https:\/\/www.southcoast.org\/\",\"name\":\"Southcoast Health\",\"description\":\"More than medicine.\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.southcoast.org\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es-MX\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Lesly Wood DNP - Southcoast Health","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.southcoast.org\/es\/doctors\/lesly-wood-dnp\/","og_locale":"es_MX","og_type":"article","og_title":"Lesly Wood DNP - Southcoast Health","og_description":"Lesly Wood, DNP, earned her Bachelor of Arts from Providence College in Providence, Rhode Island. She then went on to obtain her Associate in Science in Nursing from Bristol Community [&hellip;]","og_url":"https:\/\/www.southcoast.org\/es\/doctors\/lesly-wood-dnp\/","og_site_name":"Southcoast Health","article_modified_time":"2026-07-15T10:01:40+00:00","og_image":[{"width":150,"height":200,"url":"https:\/\/www.southcoast.org\/wp-content\/uploads\/2026\/03\/wood-lesly-150x200.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.southcoast.org\/doctors\/lesly-wood-dnp\/","url":"https:\/\/www.southcoast.org\/doctors\/lesly-wood-dnp\/","name":"Lesly Wood DNP - Southcoast Health","isPartOf":{"@id":"https:\/\/www.southcoast.org\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.southcoast.org\/doctors\/lesly-wood-dnp\/#primaryimage"},"image":{"@id":"https:\/\/www.southcoast.org\/doctors\/lesly-wood-dnp\/#primaryimage"},"thumbnailUrl":"https:\/\/www.southcoast.org\/wp-content\/uploads\/2026\/03\/wood-lesly-150x200.png","datePublished":"2026-03-31T17:47:44+00:00","dateModified":"2026-07-15T10:01:40+00:00","breadcrumb":{"@id":"https:\/\/www.southcoast.org\/doctors\/lesly-wood-dnp\/#breadcrumb"},"inLanguage":"es-MX","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.southcoast.org\/doctors\/lesly-wood-dnp\/"]}]},{"@type":"ImageObject","inLanguage":"es-MX","@id":"https:\/\/www.southcoast.org\/doctors\/lesly-wood-dnp\/#primaryimage","url":"https:\/\/www.southcoast.org\/wp-content\/uploads\/2026\/03\/wood-lesly-150x200.png","contentUrl":"https:\/\/www.southcoast.org\/wp-content\/uploads\/2026\/03\/wood-lesly-150x200.png","width":150,"height":200,"caption":"Headshot of provider Lesly Wood DNP"},{"@type":"BreadcrumbList","@id":"https:\/\/www.southcoast.org\/doctors\/lesly-wood-dnp\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"","item":"https:\/\/www.southcoast.org\/"},{"@type":"ListItem","position":2,"name":"Doctors","item":"https:\/\/www.southcoast.org\/doctors\/"},{"@type":"ListItem","position":3,"name":"Lesly Wood DNP"}]},{"@type":"WebSite","@id":"https:\/\/www.southcoast.org\/#website","url":"https:\/\/www.southcoast.org\/","name":"Southcoast Health","description":"M\u00e1s que medicina.","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.southcoast.org\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es-MX"}]}},"_links":{"self":[{"href":"https:\/\/www.southcoast.org\/es\/wp-json\/wp\/v2\/doctors\/278320","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.southcoast.org\/es\/wp-json\/wp\/v2\/doctors"}],"about":[{"href":"https:\/\/www.southcoast.org\/es\/wp-json\/wp\/v2\/types\/doctors"}],"version-history":[{"count":1,"href":"https:\/\/www.southcoast.org\/es\/wp-json\/wp\/v2\/doctors\/278320\/revisions"}],"predecessor-version":[{"id":278660,"href":"https:\/\/www.southcoast.org\/es\/wp-json\/wp\/v2\/doctors\/278320\/revisions\/278660"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.southcoast.org\/es\/wp-json\/wp\/v2\/media\/288007"}],"wp:attachment":[{"href":"https:\/\/www.southcoast.org\/es\/wp-json\/wp\/v2\/media?parent=278320"}],"wp:term":[{"taxonomy":"specialties","embeddable":true,"href":"https:\/\/www.southcoast.org\/es\/wp-json\/wp\/v2\/specialty?post=278320"},{"taxonomy":"languages","embeddable":true,"href":"https:\/\/www.southcoast.org\/es\/wp-json\/wp\/v2\/language?post=278320"},{"taxonomy":"keywords","embeddable":true,"href":"https:\/\/www.southcoast.org\/es\/wp-json\/wp\/v2\/keywords?post=278320"},{"taxonomy":"addresses","embeddable":true,"href":"https:\/\/www.southcoast.org\/es\/wp-json\/wp\/v2\/address?post=278320"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}